{"id":3211,"date":"2022-02-25T17:57:23","date_gmt":"2022-02-25T16:57:23","guid":{"rendered":"https:\/\/womenworldplatform.com\/?p=3211"},"modified":"2024-09-26T18:11:06","modified_gmt":"2024-09-26T16:11:06","slug":"8-m-vientres-de-alquiler","status":"publish","type":"post","link":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/","title":{"rendered":"8M : La maternit\u00e9 de substitution"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3211\" class=\"elementor elementor-3211\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5000e9 e-con-full e-flex e-con e-parent\" data-id=\"d5000e9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79255dd1 e-flex e-con-boxed e-con e-parent\" data-id=\"79255dd1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ad65970 elementor-widget elementor-widget-text-editor\" data-id=\"6ad65970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><div class=\"elementor-element elementor-element-ad9432f elementor-widget elementor-widget-heading\" data-id=\"ad9432f\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><h3 class=\"elementor-heading-title elementor-size-default\">8M : La maternit\u00e9 de substitution<\/h3><h5 class=\"elementor-heading-title elementor-size-default\">25 f\u00e9vrier 2022<\/h5><\/div><\/div><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42a7f5ae e-flex e-con-boxed e-con e-parent\" data-id=\"42a7f5ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-719528ff e-con-full e-flex e-con e-child\" data-id=\"719528ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b1f5dba elementor-widget elementor-widget-image\" data-id=\"7b1f5dba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"841\" src=\"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg\" class=\"attachment-full size-full wp-image-3212\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4436de98 e-flex e-con-boxed e-con e-parent\" data-id=\"4436de98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4af6fea3 e-con-full e-flex e-con e-child\" data-id=\"4af6fea3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b5fc7dd e-con-full e-flex e-con e-child\" data-id=\"7b5fc7dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-406c8ba5 elementor-widget elementor-widget-text-editor\" data-id=\"406c8ba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le 8M n'a pas de sens si la dignit\u00e9 des femmes n'est pas au centre des revendications.<\/p><p>C'est pourquoi nous accordons ces jours-ci une attention particuli\u00e8re \u00e0 la maternit\u00e9 de substitution, une forme d'exploitation des femmes et d'objectivation de la personne.<\/p><p>Nous partageons une vid\u00e9o que nous avons r\u00e9alis\u00e9e il y a quelque temps et dans laquelle nous vous parlons de la gravit\u00e9 de l'exploitation dont les femmes sont victimes dans le cadre de la maternit\u00e9 de substitution et de la fa\u00e7on dont les m\u00e8res et les b\u00e9b\u00e9s sont transform\u00e9s en objets destin\u00e9s \u00e0 \u00eatre achet\u00e9s et vendus.<\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-509d1b2 e-con-full e-flex e-con e-child\" data-id=\"509d1b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bea5d6c e-con-full e-flex e-con e-child\" data-id=\"bea5d6c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff7e6f8 elementor-widget elementor-widget-video\" data-id=\"ff7e6f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=_RbkWQBQF6g&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a352ed8 e-con-full e-flex e-con e-child\" data-id=\"7a352ed8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48b7c8af elementor-widget elementor-widget-text-editor\" data-id=\"48b7c8af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Malgr\u00e9 la gravit\u00e9 de la question, de nombreux pays ou villes dans le monde continuent d'essayer de l\u00e9galiser cette pratique, au nom d'une libert\u00e9 mal comprise qui, dans la plupart des cas, ne poursuit que des int\u00e9r\u00eats \u00e9conomiques. C'est le cas du Congr\u00e8s de la ville de Mexico, o\u00f9 des l\u00e9gislateurs de diff\u00e9rents partis politiques ont r\u00e9cemment pr\u00e9sent\u00e9 une initiative visant \u00e0 autoriser la maternit\u00e9 de substitution et ont m\u00eame l'intention de promouvoir la ville au niveau international en tant que destination id\u00e9ale pour la maternit\u00e9 de substitution.<\/p><p>A Femmes du Monde, nous r\u00e9affirmons que \"la maternit\u00e9 de substitution est incompatible avec la dignit\u00e9 des femmes et des enfants concern\u00e9s et constitue une violation de leurs droits fondamentaux\". (Conseil de l'Europe).<\/p><p>Nous vous invitons \u00e9galement \u00e0 lire et \u00e0 partager le rapport \"La maternit\u00e9 de substitution, une nouvelle forme d'exploitation des femmes et de traite des \u00eatres humains\". Dans ce rapport, vous verrez les dommages psychologiques, m\u00e9dicaux et sociaux caus\u00e9s par la maternit\u00e9 de substitution : les enfants sont transform\u00e9s en un produit commercial dont la qualit\u00e9 n'est pas contr\u00f4l\u00e9e ; les m\u00e8res porteuses deviennent une marchandise jetable ; et dans de nombreux pays, la maternit\u00e9 de substitution est invariablement li\u00e9e \u00e0 des r\u00e9seaux de prostitution.<\/p><p>De plus, cette pratique est en contradiction avec un certain nombre de normes internationales, notamment celles relatives \u00e0 la dignit\u00e9 humaine, \u00e0 l'adoption, \u00e0 la protection des femmes et des enfants et \u00e0 la traite des \u00eatres humains.<\/p><p>Vous pouvez lire le rapport ici.<\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2230b16 e-con-full e-flex e-con e-child\" data-id=\"2230b16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1a47b7 elementor-widget elementor-widget-text-editor\" data-id=\"f1a47b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maternit\u00e9 de substitution devrait \u00eatre une pratique interdite par les instruments internationaux et consid\u00e9r\u00e9e pour ce qu'elle est, c'est-\u00e0-dire une pratique qui viole les droits de l'homme.<\/p><p>Il est n\u00e9cessaire que les institutions internationales comp\u00e9tentes imposent une interdiction universelle de la gestation pour autrui, parce qu'elle pr\u00e9sente un risque r\u00e9el d'exploitation et de traite des \u00eatres humains, et parce qu'elle porte atteinte \u00e0 la dignit\u00e9 humaine en transformant les femmes et les enfants en produits commerciaux.<\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3625c9ed e-con-full e-flex e-con e-child\" data-id=\"3625c9ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e3efcad elementor-widget elementor-widget-text-editor\" data-id=\"3e3efcad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consulter le <a title=\"Ressources\" href=\"https:\/\/womenworldplatform.com\/fr\/resources\/\">ressources<\/a> en rapport avec et <a href=\"https:\/\/womenworldplatform.com\/fr\/news\/\">plus d'actualit\u00e9s<\/a> de nos actions.<\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>8M: Vientres de alquiler 25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones. Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona. Compartimos un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"give_campaign_id":0,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[33],"tags":[],"class_list":["post-3211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona.Compartimos un video que realizamos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"wowplatform\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Women of the World Platform - La voz de las mujeres que hablan en t\u00e9rminos de mujer\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"8M: Vientres de alquiler - Women of the World Platform\" \/>\n\t\t<meta property=\"og:description\" content=\"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona.Compartimos un video que realizamos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/01\/Logo-WoW.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/01\/Logo-WoW.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"397\" \/>\n\t\t<meta property=\"og:image:height\" content=\"134\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-02-25T16:57:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-26T16:11:06+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/womenworldplatform\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@Wow_platformES\" \/>\n\t\t<meta name=\"twitter:title\" content=\"8M: Vientres de alquiler - Women of the World Platform\" \/>\n\t\t<meta name=\"twitter:description\" content=\"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona.Compartimos un video que realizamos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@Wow_platformES\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/01\/Logo-WoW.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#blogposting\",\"name\":\"8M: Vientres de alquiler - Women of the World Platform\",\"headline\":\"8M: Vientres de alquiler\",\"author\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/author\\\/brechawow\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/womenworldplatform.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/8M-Vientres-de-alquiler.jpg\",\"width\":1920,\"height\":841},\"datePublished\":\"2022-02-25T17:57:23+01:00\",\"dateModified\":\"2024-09-26T18:11:06+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#webpage\"},\"articleSection\":\"Noticias\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#listItem\",\"name\":\"8M: Vientres de alquiler\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#listItem\",\"position\":3,\"name\":\"8M: Vientres de alquiler\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Noticias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/#organization\",\"name\":\"Women of the World Platform\",\"description\":\"La voz de las mujeres que hablan en t\\u00e9rminos de mujer\",\"url\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/womenworldplatform.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-WoW_Favicon.png\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/womenworldplatform\",\"https:\\\/\\\/twitter.com\\\/Wow_platformES\",\"https:\\\/\\\/www.instagram.com\\\/wowplatform\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/author\\\/brechawow\\\/#author\",\"url\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/author\\\/brechawow\\\/\",\"name\":\"wowplatform\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8937535912c804f038692db5f3387bec?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"wowplatform\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#webpage\",\"url\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/\",\"name\":\"8M: Vientres de alquiler - Women of the World Platform\",\"description\":\"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\\u00f3n estos d\\u00edas a los vientres de alquiler, una forma de explotaci\\u00f3n de la mujer y cosificaci\\u00f3n de la persona.Compartimos un video que realizamos\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/author\\\/brechawow\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/author\\\/brechawow\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/womenworldplatform.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/8M-Vientres-de-alquiler.jpg\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#mainImage\",\"width\":1920,\"height\":841},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/8-m-vientres-de-alquiler\\\/#mainImage\"},\"datePublished\":\"2022-02-25T17:57:23+01:00\",\"dateModified\":\"2024-09-26T18:11:06+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/\",\"name\":\"Women of the World Platform\",\"description\":\"La voz de las mujeres que hablan en t\\u00e9rminos de mujer\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/womenworldplatform.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"8M: Vientres de alquiler - Women of the World Platform","description":"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona.Compartimos un video que realizamos","canonical_url":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#blogposting","name":"8M: Vientres de alquiler - Women of the World Platform","headline":"8M: Vientres de alquiler","author":{"@id":"https:\/\/womenworldplatform.com\/fr\/author\/brechawow\/#author"},"publisher":{"@id":"https:\/\/womenworldplatform.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg","width":1920,"height":841},"datePublished":"2022-02-25T17:57:23+01:00","dateModified":"2024-09-26T18:11:06+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#webpage"},"isPartOf":{"@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#webpage"},"articleSection":"Noticias"},{"@type":"BreadcrumbList","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/womenworldplatform.com\/fr#listItem","position":1,"name":"Home","item":"https:\/\/womenworldplatform.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/womenworldplatform.com\/fr\/category\/noticias\/#listItem","name":"Noticias"}},{"@type":"ListItem","@id":"https:\/\/womenworldplatform.com\/fr\/category\/noticias\/#listItem","position":2,"name":"Noticias","item":"https:\/\/womenworldplatform.com\/fr\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#listItem","name":"8M: Vientres de alquiler"},"previousItem":{"@type":"ListItem","@id":"https:\/\/womenworldplatform.com\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#listItem","position":3,"name":"8M: Vientres de alquiler","previousItem":{"@type":"ListItem","@id":"https:\/\/womenworldplatform.com\/fr\/category\/noticias\/#listItem","name":"Noticias"}}]},{"@type":"Organization","@id":"https:\/\/womenworldplatform.com\/fr\/#organization","name":"Women of the World Platform","description":"La voz de las mujeres que hablan en t\u00e9rminos de mujer","url":"https:\/\/womenworldplatform.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/01\/cropped-WoW_Favicon.png","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/womenworldplatform","https:\/\/twitter.com\/Wow_platformES","https:\/\/www.instagram.com\/wowplatform\/"]},{"@type":"Person","@id":"https:\/\/womenworldplatform.com\/fr\/author\/brechawow\/#author","url":"https:\/\/womenworldplatform.com\/fr\/author\/brechawow\/","name":"wowplatform","image":{"@type":"ImageObject","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/8937535912c804f038692db5f3387bec?s=96&d=mm&r=g","width":96,"height":96,"caption":"wowplatform"}},{"@type":"WebPage","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#webpage","url":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/","name":"8M: Vientres de alquiler - Women of the World Platform","description":"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona.Compartimos un video que realizamos","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/womenworldplatform.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#breadcrumblist"},"author":{"@id":"https:\/\/womenworldplatform.com\/fr\/author\/brechawow\/#author"},"creator":{"@id":"https:\/\/womenworldplatform.com\/fr\/author\/brechawow\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg","@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#mainImage","width":1920,"height":841},"primaryImageOfPage":{"@id":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/#mainImage"},"datePublished":"2022-02-25T17:57:23+01:00","dateModified":"2024-09-26T18:11:06+02:00"},{"@type":"WebSite","@id":"https:\/\/womenworldplatform.com\/fr\/#website","url":"https:\/\/womenworldplatform.com\/fr\/","name":"Women of the World Platform","description":"La voz de las mujeres que hablan en t\u00e9rminos de mujer","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/womenworldplatform.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Women of the World Platform - La voz de las mujeres que hablan en t\u00e9rminos de mujer","og:type":"article","og:title":"8M: Vientres de alquiler - Women of the World Platform","og:description":"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona.Compartimos un video que realizamos","og:url":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/","og:image":"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/01\/Logo-WoW.png","og:image:secure_url":"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/01\/Logo-WoW.png","og:image:width":397,"og:image:height":134,"article:published_time":"2022-02-25T16:57:23+00:00","article:modified_time":"2024-09-26T16:11:06+00:00","article:publisher":"https:\/\/www.facebook.com\/womenworldplatform","twitter:card":"summary_large_image","twitter:site":"@Wow_platformES","twitter:title":"8M: Vientres de alquiler - Women of the World Platform","twitter:description":"8M: Vientres de alquiler25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones.Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona.Compartimos un video que realizamos","twitter:creator":"@Wow_platformES","twitter:image":"https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/01\/Logo-WoW.png"},"aioseo_meta_data":{"post_id":"3211","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-26 15:55:10","updated":"2025-06-03 20:09:01","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/womenworldplatform.com\/fr\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/womenworldplatform.com\/fr\/category\/noticias\/\" title=\"Noticias\">Noticias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t8M: Vientres de alquiler\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/womenworldplatform.com\/fr"},{"label":"Noticias","link":"https:\/\/womenworldplatform.com\/fr\/category\/noticias\/"},{"label":"8M: Vientres de alquiler","link":"https:\/\/womenworldplatform.com\/fr\/8-m-vientres-de-alquiler\/"}],"uagb_featured_image_src":{"full":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg",1920,841,false],"thumbnail":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-150x150.jpg",150,150,true],"medium":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-300x131.jpg",300,131,true],"medium_large":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-768x336.jpg",768,336,true],"large":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-1024x449.jpg",1024,449,true],"1536x1536":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-1536x673.jpg",1536,673,true],"2048x2048":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg",1920,841,false],"trp-custom-language-flag":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-18x8.jpg",18,8,true]},"uagb_author_info":{"display_name":"wowplatform","author_link":"https:\/\/womenworldplatform.com\/fr\/author\/brechawow\/"},"uagb_comment_info":0,"uagb_excerpt":"8M: Vientres de alquiler 25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones. Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona. Compartimos un\u2026","rttpg_featured_image_url":{"full":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg",1920,841,false],"landscape":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg",1920,841,false],"portraits":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg",1920,841,false],"thumbnail":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-150x150.jpg",150,150,true],"medium":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-300x131.jpg",300,131,true],"large":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-1024x449.jpg",1024,449,true],"1536x1536":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-1536x673.jpg",1536,673,true],"2048x2048":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler.jpg",1920,841,false],"trp-custom-language-flag":["https:\/\/womenworldplatform.com\/wp-content\/uploads\/2024\/09\/8M-Vientres-de-alquiler-18x8.jpg",18,8,true]},"rttpg_author":{"display_name":"wowplatform","author_link":"https:\/\/womenworldplatform.com\/fr\/author\/brechawow\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/womenworldplatform.com\/fr\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"8M: Vientres de alquiler 25 de febrero de 2022 El 8M no tiene sentido si la dignidad de la mujer no est\u00e1 en el centro de las reivindicaciones. Por eso le dedicamos especial atenci\u00f3n estos d\u00edas a los vientres de alquiler, una forma de explotaci\u00f3n de la mujer y cosificaci\u00f3n de la persona. Compartimos un\u2026","_links":{"self":[{"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/posts\/3211"}],"collection":[{"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/comments?post=3211"}],"version-history":[{"count":5,"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/posts\/3211\/revisions"}],"predecessor-version":[{"id":3217,"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/posts\/3211\/revisions\/3217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/media\/3212"}],"wp:attachment":[{"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/media?parent=3211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/categories?post=3211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/womenworldplatform.com\/fr\/wp-json\/wp\/v2\/tags?post=3211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}